{"id":2503,"date":"2020-08-07T11:38:23","date_gmt":"2020-08-07T08:38:23","guid":{"rendered":"https:\/\/www.turkishtranslationoffice.com\/tr\/entegrasyonlar-copy\/"},"modified":"2022-02-08T10:46:53","modified_gmt":"2022-02-08T07:46:53","slug":"belge-tercumesi","status":"publish","type":"page","link":"https:\/\/www.turkishtranslationoffice.com\/tr\/belge-tercumesi\/","title":{"rendered":"Belge Terc\u00fcmesi"},"content":{"rendered":"<p>[vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-default&#8221; bg_image_new=&#8221;id^3190|url^https:\/\/www.turkishtranslationoffice.com\/tr\/wp-content\/uploads\/2020\/08\/belge-tercumesi.jpg|caption^null|alt^null|title^belge-tercumesi|description^null&#8221; bg_image_repeat=&#8221;no-repeat&#8221; bg_override=&#8221;ex-full&#8221; type=&#8221;vc_default&#8221; margin_top=&#8221;5&#8243; margin_bottom=&#8221;10&#8243; css=&#8221;.vc_custom_1629972296245{padding-top: 2% !important;padding-bottom: 2% !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;]<div id=\"ultimate-heading-69906a04b48ca970d\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-69906a04b48ca970d uvc-7255 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-69906a04b48ca970d h1'  data-responsive-json-new='{\"font-size\":\"desktop:28px;\",\"line-height\":\"desktop:34px;\"}' ><h1 style=\"font-weight:bold;margin-bottom:25px;\">Resmi Evrak Terc\u00fcmesinde Uygun Fiyat, G\u00fcvenilir Hizmet<\/h1><\/div><\/div>[vc_column_text]<\/p>\n<p style=\"text-align: left;\"><span style=\"font-weight: 400; font-size: 18px;\">Belge \u00e7evirisine ihtiya\u00e7 duydu\u011funuz her alanda ve t\u00fcm dillerde Turkish Translation Office g\u00fcvencesi!<\/span><\/p>\n<p><span style=\"font-weight: 400; font-size: 18px;\">Bankac\u0131l\u0131k evraklar\u0131ndan e\u011fitim ve kariyeriniz i\u00e7in gerekli belgelere, ticari belgelerinizden kimlik belgelerine kadar t\u00fcm dosya t\u00fcrlerinde kaliteli evrak terc\u00fcmesi hizmetleri sunuyoruz\u2026<\/span>[\/vc_column_text][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221;][vc_column_inner css=&#8221;.vc_custom_1644306403686{padding-top: 20px !important;padding-bottom: 32px !important;}&#8221;]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">#default-btn-8e96716c7989ea5f583ac5739d3008ec.ico-right-side > i {\n  margin-right: 0px;\n  margin-left: 8px;\n}\n#default-btn-8e96716c7989ea5f583ac5739d3008ec > i {\n  margin-right: 8px;\n}\n#default-btn-8e96716c7989ea5f583ac5739d3008ec * {\n  vertical-align: middle;\n}\n<\/style><a href=\"\/tr\/teklif-alin\/\" class=\"default-btn-shortcode dt-btn dt-btn-l link-hover-off button-tto-grey btn-inline-left  vc_custom_1600265126258\" id=\"default-btn-8e96716c7989ea5f583ac5739d3008ec\" style=\"width:225px;\"><span>\u00dccretsiz Teklif Al\u0131n<\/span><\/a><style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">#default-btn-4fd15a2a35a1635efab2bd48ce2416a1.ico-right-side > i {\n  margin-right: 0px;\n  margin-left: 8px;\n}\n#default-btn-4fd15a2a35a1635efab2bd48ce2416a1 > i {\n  margin-right: 8px;\n}\n#default-btn-4fd15a2a35a1635efab2bd48ce2416a1 * {\n  vertical-align: middle;\n}\n<\/style><a href=\"\/tr\/iletisim\/\" class=\"default-btn-shortcode dt-btn dt-btn-l link-hover-off button-tto-red btn-inline-left  vc_custom_1600265139056\" id=\"default-btn-4fd15a2a35a1635efab2bd48ce2416a1\" style=\"width:225px;\"><span>Bize Ula\u015f\u0131n<\/span><\/a>[\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; bg_type=&#8221;bg_color&#8221; bg_override=&#8221;ex-full&#8221; type=&#8221;vc_default&#8221; margin_top=&#8221;5&#8243; margin_bottom=&#8221;10&#8243; css=&#8221;.vc_custom_1598012359927{padding-top: 30px !important;padding-bottom: 30px !important;}&#8221; bg_color_value=&#8221;#f4f4f4&#8243;][vc_column css=&#8221;.vc_custom_1491746299333{padding-bottom: 0px !important;}&#8221;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221;][vc_column_inner width=&#8221;1\/2&#8243;]<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">.shortcode-single-image-wrap.shortcode-single-image-8227597ab90ce8e94ec2c09e11d0d20e.enable-bg-rollover .rollover i,\n.shortcode-single-image-wrap.shortcode-single-image-8227597ab90ce8e94ec2c09e11d0d20e.enable-bg-rollover .rollover-video i {\n  background: ;\n  background: -webkit-linear-gradient();\n  background: linear-gradient();\n}\n.shortcode-single-image-wrap.shortcode-single-image-8227597ab90ce8e94ec2c09e11d0d20e .rollover-icon {\n  font-size: 32px;\n  color: #ffffff;\n  min-width: 44px;\n  min-height: 44px;\n  line-height: 44px;\n  border-radius: 100px;\n  border-style: solid;\n  border-width: 0px;\n}\n.dt-icon-bg-on.shortcode-single-image-wrap.shortcode-single-image-8227597ab90ce8e94ec2c09e11d0d20e .rollover-icon {\n  background: rgba(255,255,255,0.3);\n  box-shadow: none;\n}\n<\/style><div class=\"shortcode-single-image-wrap shortcode-single-image-8227597ab90ce8e94ec2c09e11d0d20e alignnone  enable-bg-rollover dt-icon-bg-off\" style=\"margin-top:0px; margin-bottom:0px; margin-left:0px; margin-right:0px; width:1000px;\"><div class=\"shortcode-single-image\"><div class=\"fancy-media-wrap  layzr-bg\" style=\"border-radius:10px;\"><img loading=\"lazy\" decoding=\"async\" class=\"preload-me lazy-load\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D&#39;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#39;%20viewBox%3D&#39;0%200%201000%20700&#39;%2F%3E\" data-src=\"https:\/\/www.turkishtranslationoffice.com\/tr\/wp-content\/uploads\/sites\/1\/2020\/08\/resmi-evrak-tercumesine-ihtiyac-1-1000x700.jpg\" data-srcset=\"https:\/\/www.turkishtranslationoffice.com\/tr\/wp-content\/uploads\/sites\/1\/2020\/08\/resmi-evrak-tercumesine-ihtiyac-1-1000x700.jpg 1000w, https:\/\/www.turkishtranslationoffice.com\/tr\/wp-content\/uploads\/sites\/1\/2020\/08\/resmi-evrak-tercumesine-ihtiyac-1-1524x1067.jpg 1524w\" width=\"1000\" height=\"700\"  data-dt-location=\"https:\/\/www.turkishtranslationoffice.com\/tr\/belge-tercumesi\/resmi-evrak-tercumesine-ihtiyac\/\" style=\"border-radius:10px;\" alt=\"Resmi belge terc\u00fcmesi\" \/><\/div><\/div><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243; css=&#8221;.vc_custom_1596550089277{padding-top: 20px !important;}&#8221;]<div id=\"ultimate-heading-93116a04b48ca9e10\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-93116a04b48ca9e10 uvc-7749 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-93116a04b48ca9e10 h2'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"desktop:34px;\"}' ><h2 style=\"font-weight:bold;margin-bottom:25px;\">Resmi belge terc\u00fcmesine ne zaman ihtiya\u00e7 duyulur?<\/h2><\/div><\/div><div class=\"standard-arrow bullet-top\"><ul>\n<li><span style=\"font-weight: 400;\">Yurt d\u0131\u015f\u0131nda bir i\u015fe\/okula ba\u015flarken<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Uluslararas\u0131 ticari ve finansal i\u015flemler s\u0131ras\u0131nda<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Kimlik ve yerle\u015fim yeri g\u00f6steren belgelerinin terc\u00fcmesinde<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Mahkeme, dava gibi yasal s\u00fcre\u00e7ler s\u0131ras\u0131nda<\/span><\/li>\n<\/ul>\n<\/div>[vc_column_text]<span style=\"font-weight: 400;\">Terminolojiye hakim, uzman terc\u00fcmanlar\u0131m\u0131zla sundu\u011fumuz yeminli terc\u00fcme hizmetlerimizden yararlan\u0131n, hatal\u0131 ya da eksik \u00e7eviri riskinden kurtulun! Kalite sertifikalar\u0131na sahip terc\u00fcme b\u00fcromuzda t\u00fcm evraklar\u0131n\u0131z i\u00e7in h\u0131zl\u0131 ve g\u00fcvenilir \u00e7eviri \u00e7\u00f6z\u00fcmleri sunuyoruz.<\/span><\/p>\n<ul>\n<li><span style=\"font-weight: 400;\">Turkish Translation Office olarak 2500\u2019\u00fcn \u00fczerinde profesyonel dil uzman\u0131m\u0131z aras\u0131ndan \u00e7evirinizde tecr\u00fcbe sahibi yeminli terc\u00fcmanlar\u0131 g\u00f6revlendiriyoruz.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">\u00c7evirinizi herhangi bir hata ya da eksik \u00e7eviriye kar\u015f\u0131 edit\u00f6rlerimiz arac\u0131l\u0131\u011f\u0131yla kontrol ediyoruz.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Terc\u00fcme edilen belgelerinizi size en h\u0131zl\u0131 \u015fekilde ula\u015ft\u0131rma s\u00f6z\u00fc veriyoruz. <\/span><\/li>\n<li><span style=\"font-weight: 400;\">Terc\u00fcmenin t\u00fcm alanlar\u0131nda uzman ekiplerimizi dil uzmanlar\u0131, proje y\u00f6neticileri ve masa\u00fcst\u00fc yay\u0131nc\u0131l\u0131k profesyonellerinden olu\u015fturuyoruz.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">\u00c7eviri projelerinizi 7\/24 online olarak m\u00fc\u015fteri portal\u0131m\u0131zdan y\u00f6netme ayr\u0131cal\u0131\u011f\u0131 sa\u011fl\u0131yor ve size zaman kazand\u0131r\u0131yoruz.<\/span><\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row][vc_row bg_type=&#8221;grad&#8221; bg_override=&#8221;ex-full&#8221; bg_grad=&#8221;background: -webkit-gradient(linear, left top, left bottom, color-stop(0%, #365088), color-stop(100%, #EA524D));background: -moz-linear-gradient(135deg,#365088 0%,#EA524D 100%);background: -webkit-linear-gradient(135deg,#365088 0%,#EA524D 100%);background: -o-linear-gradient(135deg,#365088 0%,#EA524D 100%);background: -ms-linear-gradient(135deg,#365088 0%,#EA524D 100%);background: linear-gradient(135deg,#365088 0%,#EA524D 100%);&#8221;][vc_column]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin   vc_custom_1596535225225\"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:96px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:32px;border-width:1px;border-style:none;background:#ffffff;color:#d44133;border-color:#333333;\"><i class=\"fas fa-handshake\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5926\" style=\"font-size:32px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5926 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"font-weight:bold;color:#ffffff;\">G\u00fcvenilir Hizmet<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5926 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"color:#ffffff;\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:96px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:32px;border-width:1px;border-style:none;background:#ffffff;color:#d44133;border-color:#333333;\"><i class=\"fas fa-users\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-6481\" style=\"font-size:32px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-6481 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"font-weight:bold;color:#ffffff;\">Profesyonel Ekipler<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-6481 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"color:#ffffff;\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:96px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:32px;border-width:1px;border-style:none;background:#ffffff;color:#d44133;border-color:#333333;\"><i class=\"fas fa-comments\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-1489\" style=\"font-size:32px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-1489 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"font-weight:bold;color:#ffffff;\">7 \/ 24 Online \u00c7eviri<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-1489 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"color:#ffffff;\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:96px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:32px;border-width:1px;border-style:none;background:#ffffff;color:#d44133;border-color:#333333;\"><i class=\"fas fa-thumbs-up\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-2545\" style=\"font-size:32px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-2545 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"font-weight:bold;color:#ffffff;\">Kaliteli ve Eksiksiz \u00c7eviri<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-2545 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"color:#ffffff;\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><li class=\"icon_list_item\" style=\" font-size:96px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:32px;border-width:1px;border-style:none;background:#ffffff;color:#d44133;border-color:#333333;\"><i class=\"fas fa-tachometer-alt\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-8055\" style=\"font-size:32px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-8055 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"font-weight:bold;color:#ffffff;\">Acil Terc\u00fcmede H\u0131zl\u0131 Teslim<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-8055 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"color:#ffffff;\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column][\/vc_row][vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-hz-jquery&#8221; bg_image_new=&#8221;id^1611|url^https:\/\/www.turkishtranslationoffice.com\/tr\/wp-content\/uploads\/2016\/02\/bg-mem.png|caption^null|alt^null|title^bg-mem|description^null&#8221; bg_override=&#8221;ex-full&#8221; type=&#8221;vc_default&#8221; margin_top=&#8221;5&#8243; margin_bottom=&#8221;10&#8243; css=&#8221;.vc_custom_1598012316823{padding-top: 50px !important;padding-bottom: 30px !important;background-color: #f4f4f4 !important;}&#8221;][vc_column]<div id=\"ultimate-heading-21526a04b48ca9f4f\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-21526a04b48ca9f4f uvc-9030 \" data-hspacer=\"no_spacer\"  data-halign=\"center\" style=\"text-align:center\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-21526a04b48ca9f4f h3'  data-responsive-json-new='{\"font-size\":\"desktop:24px;\",\"line-height\":\"desktop:34px;\"}' ><h3 style=\"font-weight:bold;margin-bottom:25px;\">Belge \u00c7evirisinde En S\u0131k Terc\u00fcme Edilen Evraklar<\/h3><\/div><\/div>[vc_separator color=&#8221;custom&#8221; border_width=&#8221;2&#8243; el_width=&#8221;10&#8243; accent_color=&#8221;#d44133&#8243;][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; gap=&#8221;35&#8243;][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-1105\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-1105 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Adli sicil kayd\u0131<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-1105 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-3787\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-3787 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Kimlik\/n\u00fcfus kay\u0131t \u00f6rne\u011fi<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-3787 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-4427\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-4427 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Pasaport<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-4427 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-3435\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-3435 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Ehliyet<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-3435 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; gap=&#8221;35&#8243; css=&#8221;.vc_custom_1596795187832{padding-top: -20px !important;}&#8221;][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-9304\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-9304 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">\u0130kametgah<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-9304 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-4569\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-4569 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Askerlik belgesi<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-4569 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7550\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7550 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Evlilik belgeleri<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7550 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-7839\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-7839 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Sa\u011fl\u0131k raporu<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-7839 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; gap=&#8221;35&#8243;][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5278\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5278 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Diploma, transkript ve \u00f6\u011frenci belgesi<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5278 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-3649\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-3649 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Ticari belgeler<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-3649 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-8458\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-8458 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Muvafakatname<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-8458 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-8108\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-8108 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">\u0130mza sirk\u00fcleri<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-8108 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][\/vc_row_inner][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; gap=&#8221;35&#8243;][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5645\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5645 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Vekaletname<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5645 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-5908\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-5908 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">\u0130\u015fe al\u0131m s\u00f6zle\u015fmesi<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-5908 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-6710\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-6710 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">Faaliyet belgesi<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-6710 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][vc_column_inner width=&#8221;1\/4&#8243;]<div class=\"smile_icon_list_wrap ult_info_list_container ult-adjust-bottom-margin  \"><ul class=\"smile_icon_list top circle with_bg\"><li class=\"icon_list_item\" style=\" font-size:84px;\"><div class=\"icon_list_icon\" data-animation=\"\" data-animation-delay=\"03\" style=\"font-size:28px;border-width:1px;border-style:dashed;background:#f4f4f4;color:#d44133;border-color:#333333;\"><i class=\"fas fa-check\" ><\/i><\/div><div class=\"icon_description\" id=\"Info-list-wrap-8246\" style=\"font-size:28px;\"><h3 class=\"ult-responsive info-list-heading\"  data-ultimate-target='#Info-list-wrap-8246 h3'  data-responsive-json-new='{\"font-size\":\"desktop:16px;\",\"line-height\":\"desktop:24px;\"}'  style=\"\">S\u00f6zle\u015fmeler<\/h3><div class=\"icon_description_text ult-responsive\"  data-ultimate-target='#Info-list-wrap-8246 .icon_description_text'  data-responsive-json-new='{\"font-size\":\"desktop:13px;\",\"line-height\":\"desktop:18px;\"}'  style=\"\"><\/div><\/div><div class=\"icon_list_connector\" data-animation=\"fadeInLeft\" data-animation-delay=\"03\" style=\"border: none !important;\"><\/div><\/li><\/ul><\/div>[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221; bg_type=&#8221;image&#8221; parallax_style=&#8221;vcpb-default&#8221; bg_image_new=&#8221;id^3190|url^https:\/\/www.turkishtranslationoffice.com\/tr\/wp-content\/uploads\/2020\/08\/belge-tercumesi.jpg|caption^null|alt^null|title^belge-tercumesi|description^null&#8221; bg_image_repeat=&#8221;no-repeat&#8221; bg_override=&#8221;ex-full&#8221; type=&#8221;vc_default&#8221; margin_top=&#8221;5&#8243; margin_bottom=&#8221;10&#8243; css=&#8221;.vc_custom_1629972296245{padding-top: 2% !important;padding-bottom: 2% !important;}&#8221;][vc_column width=&#8221;1\/2&#8243;][vc_column_text] Belge \u00e7evirisine ihtiya\u00e7 duydu\u011funuz her alanda ve t\u00fcm dillerde Turkish Translation Office g\u00fcvencesi! Bankac\u0131l\u0131k evraklar\u0131ndan e\u011fitim ve kariyeriniz i\u00e7in gerekli belgelere, ticari belgelerinizden kimlik belgelerine kadar t\u00fcm dosya t\u00fcrlerinde kaliteli evrak terc\u00fcmesi hizmetleri sunuyoruz\u2026[\/vc_column_text][vc_row_inner equal_height=&#8221;yes&#8221; content_placement=&#8221;top&#8221;][vc_column_inner css=&#8221;.vc_custom_1644306403686{padding-top: 20px&hellip;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.turkishtranslationoffice.com\/tr\/wp-json\/wp\/v2\/pages\/2503"}],"collection":[{"href":"https:\/\/www.turkishtranslationoffice.com\/tr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.turkishtranslationoffice.com\/tr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.turkishtranslationoffice.com\/tr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.turkishtranslationoffice.com\/tr\/wp-json\/wp\/v2\/comments?post=2503"}],"version-history":[{"count":3,"href":"https:\/\/www.turkishtranslationoffice.com\/tr\/wp-json\/wp\/v2\/pages\/2503\/revisions"}],"predecessor-version":[{"id":5622,"href":"https:\/\/www.turkishtranslationoffice.com\/tr\/wp-json\/wp\/v2\/pages\/2503\/revisions\/5622"}],"wp:attachment":[{"href":"https:\/\/www.turkishtranslationoffice.com\/tr\/wp-json\/wp\/v2\/media?parent=2503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}